{"id":8169,"date":"2026-04-27T03:19:25","date_gmt":"2026-04-27T03:19:25","guid":{"rendered":"https:\/\/prillumenlight.com\/?post_type=avada_portfolio&#038;p=8169"},"modified":"2026-04-27T03:19:25","modified_gmt":"2026-04-27T03:19:25","slug":"4ft-hospital-overbed-light","status":"publish","type":"avada_portfolio","link":"https:\/\/prillumenlight.com\/fr\/product\/4ft-hospital-overbed-light\/","title":{"rendered":"Lampe de chevet d'h\u00f4pital de 4 pieds"},"content":{"rendered":"<h1 data-path-to-node=\"2\">Fournisseur d'usine de lumi\u00e8re de lit d'h\u00f4pital de 4FT<code data-path-to-node=\"3\" data-index-in-node=\"5\"><\/code><\/h1>\n<h2 data-path-to-node=\"5\">1. La norme de l'industrie pour une couverture maximale<\/h2>\n<p data-path-to-node=\"6\">Le <b data-path-to-node=\"6\" data-index-in-node=\"4\">4FT <a href=\"https:\/\/prillumenlight.com\/fr\/applications\/medical-lighting-suppliers\/\">Hospital Overbed<\/a> Light<\/b> (1200mm) est la taille la plus largement sp\u00e9cifi\u00e9e pour les salles d'h\u00f4pital standard et les chambres doubles \u00e0 l'\u00e9chelle mondiale. Con\u00e7ue pour offrir une couverture en largeur compl\u00e8te sur des lits d'h\u00f4pital de taille standard, cette installation de 48 pouces garantit qu'il n'y a pas de \u201c zones d'ombre \u201d dans l'environnement du patient.<\/p>\n<p data-path-to-node=\"7\">As a high-capacity <b data-path-to-node=\"7\" data-index-in-node=\"19\">Fabricant bas\u00e9 en Chine<\/b>, Prillumen a con\u00e7u la s\u00e9rie 4FT pour r\u00e9sister aux exigences rigoureuses et 24\/7 des h\u00f4pitaux publics tout en offrant la plus haute luminosit\u00e9 dans notre <b data-path-to-node=\"7\" data-index-in-node=\"194\">l'\u00e9clairage des soins de sant\u00e9<\/b> catalogue.<\/p>\n<p data-path-to-node=\"7\"><img decoding=\"async\" class=\"lazyload alignnone size-full wp-image-8170\" src=\"https:\/\/prillumenlight.com\/wp-content\/uploads\/2026\/04\/4FT-Hospital-Overbed-Light.webp\" data-orig-src=\"https:\/\/prillumenlight.com\/wp-content\/uploads\/2026\/04\/4FT-Hospital-Overbed-Light.webp\" alt=\"Lampe de chevet d&#039;h\u00f4pital de 4 pieds\" width=\"600\" height=\"600\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27600%27%20viewBox%3D%270%200%20600%20600%27%3E%3Crect%20width%3D%27600%27%20height%3D%27600%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/prillumenlight.com\/wp-content\/uploads\/2026\/04\/4FT-Hospital-Overbed-Light-12x12.webp 12w, https:\/\/prillumenlight.com\/wp-content\/uploads\/2026\/04\/4FT-Hospital-Overbed-Light-66x66.webp 66w, https:\/\/prillumenlight.com\/wp-content\/uploads\/2026\/04\/4FT-Hospital-Overbed-Light-150x150.webp 150w, https:\/\/prillumenlight.com\/wp-content\/uploads\/2026\/04\/4FT-Hospital-Overbed-Light-200x200.webp 200w, https:\/\/prillumenlight.com\/wp-content\/uploads\/2026\/04\/4FT-Hospital-Overbed-Light-300x300.webp 300w, https:\/\/prillumenlight.com\/wp-content\/uploads\/2026\/04\/4FT-Hospital-Overbed-Light-400x400.webp 400w, https:\/\/prillumenlight.com\/wp-content\/uploads\/2026\/04\/4FT-Hospital-Overbed-Light.webp 600w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p>\n<h2 data-path-to-node=\"9\">2. Performance phare : Sp\u00e9cification de haute puissance de 60W<\/h2>\n<p data-path-to-node=\"10\">Lorsque la pr\u00e9cision clinique est non n\u00e9gociable, le mod\u00e8le 4FT fournit la puissance et la fiabilit\u00e9 n\u00e9cessaires pour des environnements complexes <b data-path-to-node=\"10\" data-index-in-node=\"113\">exigences d'examen<\/b>.<\/p>\n<table data-path-to-node=\"11\">\n<thead>\n<tr>\n<td><strong>Fonctionnalit\u00e9<\/strong><\/td>\n<td><strong>Sp\u00e9cification<\/strong><\/td>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td><span data-path-to-node=\"11,1,0,0\"><b data-path-to-node=\"11,1,0,0\" data-index-in-node=\"0\">Longueur physique<\/b><\/span><\/td>\n<td><span data-path-to-node=\"11,1,1,0\">48,58\u2033 (environ 1230mm)<\/span><\/td>\n<\/tr>\n<tr>\n<td><span data-path-to-node=\"11,2,0,0\"><b data-path-to-node=\"11,2,0,0\" data-index-in-node=\"0\">Puissance du syst\u00e8me<\/b><\/span><\/td>\n<td><span data-path-to-node=\"11,2,1,0\">60W (Intensit\u00e9 clinique maximale)<\/span><\/td>\n<\/tr>\n<tr>\n<td><span data-path-to-node=\"11,3,0,0\"><b data-path-to-node=\"11,3,0,0\" data-index-in-node=\"0\">Lumen Efficacy<\/b><\/span><\/td>\n<td><span data-path-to-node=\"11,3,1,0\">115 lm\/W<\/span><\/td>\n<\/tr>\n<tr>\n<td><span data-path-to-node=\"11,4,0,0\"><b data-path-to-node=\"11,4,0,0\" data-index-in-node=\"0\">Lumens totaux<\/b><\/span><\/td>\n<td><span data-path-to-node=\"11,4,1,0\">6 900 lumens<\/span><\/td>\n<\/tr>\n<tr>\n<td><span data-path-to-node=\"11,5,0,0\"><b data-path-to-node=\"11,5,0,0\" data-index-in-node=\"0\">Distribution lumineuse<\/b><\/span><\/td>\n<td><span data-path-to-node=\"11,5,1,0\">Downlight 60% \/ Uplight 40% (Standard)<\/span><\/td>\n<\/tr>\n<tr>\n<td><span data-path-to-node=\"11,6,0,0\"><b data-path-to-node=\"11,6,0,0\" data-index-in-node=\"0\">Construction<\/b><\/span><\/td>\n<td><span data-path-to-node=\"11,6,1,0\">Aluminium extrud\u00e9 de qualit\u00e9 industrielle<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2 data-path-to-node=\"13\">3. Principaux avantages pour les \u00e9tablissements de sant\u00e9 \u00e0 grande \u00e9chelle<\/h2>\n<h3 data-path-to-node=\"14\">A. Couverture maximale du champ d'examen<\/h3>\n<p data-path-to-node=\"15\">Avec 6 900 lumens en sortie maximale, l'appareil de 4FT offre une couverture expansive <b data-path-to-node=\"15\" data-index-in-node=\"72\">mode examen<\/b> champ de lumi\u00e8re. Cela permet aux m\u00e9decins et aux infirmiers d'effectuer des proc\u00e9dures avec une clart\u00e9 absolue, en veillant \u00e0 minimiser les ombres dans tout l'espace clinique de 4 pieds.<\/p>\n<h3 data-path-to-node=\"16\">B. Contr\u00f4le sup\u00e9rieur de l'\u00e9blouissement pour les chambres partag\u00e9es<\/h3>\n<p data-path-to-node=\"17\">Dans les chambres \u00e0 double patient, la diffusion de la lumi\u00e8re peut poser un probl\u00e8me majeur. Notre s\u00e9rie 4FT <b data-path-to-node=\"17\" data-index-in-node=\"65\">lighting fixtures<\/b> utilise des lentilles avanc\u00e9es <b data-path-to-node=\"17\" data-index-in-node=\"100\">diffuseurs de lumi\u00e8re<\/b> et micro-prismatiques pour garantir que, tout en \u00e9clairant brillamment le lit pr\u00e9vu, l'\u00e9blouissement reste contr\u00f4l\u00e9 afin de prot\u00e9ger le confort du patient dans le lit adjacent.<\/p>\n<h3 data-path-to-node=\"18\">C. Durabilit\u00e9 de qualit\u00e9 industrielle<\/h3>\n<p data-path-to-node=\"19\">Les h\u00f4pitaux publics exigent <b data-path-to-node=\"19\" data-index-in-node=\"25\">luminaires<\/b> qui sont con\u00e7us pour durer. Notre s\u00e9rie 4FT dispose d'un bo\u00eetier r\u00e9sistant aux impacts et d'un <b data-path-to-node=\"19\" data-index-in-node=\"129\">fini antimicrobien<\/b> r\u00e9sistant aux protocoles de d\u00e9sinfection chimique les plus agressifs utilis\u00e9s dans les \u00e9tablissements \u00e0 fort trafic. <b data-path-to-node=\"19\" data-index-in-node=\"234\">en environnement de soins de sant\u00e9<\/b>.<\/p>\n<hr data-path-to-node=\"20\" \/>\n<h2 data-path-to-node=\"21\">4. Sc\u00e9narios d'application principaux<\/h2>\n<h3 data-path-to-node=\"22\">\ud83c\udfe5 Salles g\u00e9n\u00e9rales d'h\u00f4pitaux publics<\/h3>\n<p data-path-to-node=\"23\">Le mod\u00e8le de 48 pouces est la norme privil\u00e9gi\u00e9e pour les projets d'h\u00f4pitaux publics et gouvernementaux en raison de sa capacit\u00e9 \u00e0 fournir <b data-path-to-node=\"23\" data-index-in-node=\"118\">un \u00e9clairage ad\u00e9quat<\/b> \u00e0 la fois pour les soins g\u00e9n\u00e9raux aux patients et pour les interventions d'urgence au chevet.<\/p>\n<h3 data-path-to-node=\"24\">\ud83d\udecc Chambres doubles\/multi-occupants<\/h3>\n<p data-path-to-node=\"25\">La longueur de l'appareil 4FT le rend id\u00e9al pour les chambres o\u00f9 les lits sont plac\u00e9s proches les uns des autres, car un seul appareil peut souvent servir de source lumineuse principale pour la zone imm\u00e9diate au chevet.<\/p>\n<h3 data-path-to-node=\"26\">\ud83e\uddea Unit\u00e9s cliniques sp\u00e9cialis\u00e9es<\/h3>\n<p data-path-to-node=\"27\">Parfait pour les centres de traumatologie, les unit\u00e9s de r\u00e9cup\u00e9ration chirurgicale et les zones de soins intensifs o\u00f9 le <b data-path-to-node=\"27\" data-index-in-node=\"88\">exigences d'examen<\/b> est \u00e0 son maximum.<\/p>\n<h2 data-path-to-node=\"29\">5. Support en gros et pour projets depuis notre usine<\/h2>\n<p data-path-to-node=\"30\">Prillumen se sp\u00e9cialise dans le soutien aux appels d'offres \u00e0 grande \u00e9chelle et aux achats en gros pour les groupes hospitaliers internationaux.<\/p>\n<ul data-path-to-node=\"31\">\n<li>\n<p data-path-to-node=\"31,0,0\"><b data-path-to-node=\"31,0,0\" data-index-in-node=\"0\">Logistique pr\u00eate pour le projet :<\/b> Nous proposons un emballage optimis\u00e9 pour les unit\u00e9s de 1200 mm afin d'assurer un transport international s\u00fbr et \u00e0 faible co\u00fbt pour les commandes de plus de 500 unit\u00e9s.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"31,1,0\"><b data-path-to-node=\"31,1,0\" data-index-in-node=\"0\">Conformit\u00e9 totale :<\/b> Nos luminaires de 4FT sont <b data-path-to-node=\"31,1,0\" data-index-in-node=\"38\">UL\/cUL Certifi\u00e9<\/b> et respectent <b data-path-to-node=\"31,1,0\" data-index-in-node=\"61\">DLC Premium<\/b> les normes, maximisant ainsi les remises \u00e9nerg\u00e9tiques pour les r\u00e9novations de grandes installations.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"31,2,0\"><b data-path-to-node=\"31,2,0\" data-index-in-node=\"0\">Soumissions d'experts :<\/b> Nous fournissons toute la documentation n\u00e9cessaire, y compris les fichiers IES, les rapports de tests thermiques, et <b data-path-to-node=\"31,2,0\" data-index-in-node=\"106\">fini antimicrobien<\/b> les certifications pour vous aider \u00e0 remporter votre prochain appel d'offres.<\/p>\n<\/li>\n<\/ul>\n<h2 data-path-to-node=\"33\">6. FAQ Professionnelle de la s\u00e9rie 4FT<\/h2>\n<p data-path-to-node=\"34\"><b data-path-to-node=\"34\" data-index-in-node=\"0\">Q : Un luminaire de 4FT est-il trop lumineux pour un seul patient ?<\/b><\/p>\n<p data-path-to-node=\"34\">R : Pas du tout. Gr\u00e2ce \u00e0 la <b data-path-to-node=\"34\" data-index-in-node=\"82\">contr\u00f4le ind\u00e9pendant haut-bas<\/b>, le patient peut utiliser la lumi\u00e8re douce <b data-path-to-node=\"34\" data-index-in-node=\"140\">mode ambiant<\/b> (uplight) pour un environnement relaxant. La puissance compl\u00e8te de 60W n'est activ\u00e9e que lors de <b data-path-to-node=\"34\" data-index-in-node=\"233\">mode examen<\/b> ou lorsque la lumi\u00e8re \u00e0 haute intensit\u00e9 est cliniquement n\u00e9cessaire.<\/p>\n<p data-path-to-node=\"35\"><b data-path-to-node=\"35\" data-index-in-node=\"0\">Q : Comment le poids du mod\u00e8le 4FT influence-t-il l'installation ?<\/b><\/p>\n<p data-path-to-node=\"35\">R : Malgr\u00e9 sa construction en aluminium robuste, le luminaire reste suffisamment l\u00e9ger pour une installation par une seule personne. La <b data-path-to-node=\"35\" data-index-in-node=\"187\">fixation murale<\/b> Le syst\u00e8me de support est con\u00e7u pour un alignement rapide sur des bo\u00eetes \u00e9lectriques standard.<\/p>\n<p data-path-to-node=\"36\"><b data-path-to-node=\"36\" data-index-in-node=\"0\">Q : Pouvons-nous commander ces produits avec une batterie d'urgence int\u00e9gr\u00e9e (EM) ?<\/b><\/p>\n<p data-path-to-node=\"36\">R : Oui. Pour les grands projets hospitaliers, nous pouvons \u00e9quiper la s\u00e9rie 4FT d'un pilote EM interne qui fournit 90 minutes de <b data-path-to-node=\"36\" data-index-in-node=\"185\">un \u00e9clairage ad\u00e9quat<\/b> en cas de panne de courant, respectant tous les codes de s\u00e9curit\u00e9 de vie.<\/p>\n<p data-path-to-node=\"37\"><b data-path-to-node=\"37\" data-index-in-node=\"0\">Q : Le mod\u00e8le 4FT est-il s\u00e9lectionnable en CCT ?<\/b><\/p>\n<p data-path-to-node=\"37\">R : Oui. Comme nos autres mod\u00e8les, la version 4FT dispose <b data-path-to-node=\"37\" data-index-in-node=\"92\">temp\u00e9rature de couleur (CCT) selectable<\/b> d'interrupteurs, vous permettant de choisir entre 3000K, 4000K ou 5000K pour s'harmoniser avec l\u2019\u00e9clairage existant dans votre \u00e9tablissement.<\/p>\n<h2 data-path-to-node=\"39\">7. Faites \u00e9voluer votre \u00e9tablissement avec Prillumen<\/h2>\n<p data-path-to-node=\"40\">Pour des performances \u00e9lev\u00e9es, une durabilit\u00e9 accrue et une grande valeur <b data-path-to-node=\"40\" data-index-in-node=\"54\">luminaires de chevet pour h\u00f4pital<\/b>, la s\u00e9rie Prillumen 4FT est le premier choix des sp\u00e9cialistes en conception d\u2019\u00e9clairage professionnel.<\/p>\n<p data-path-to-node=\"43\"><b data-path-to-node=\"43\" data-index-in-node=\"0\">Prillumen : Alimenter l'avenir des soins de sant\u00e9 publics.<\/b><\/p>\n<p data-path-to-node=\"43\"><i data-path-to-node=\"43\" data-index-in-node=\"53\">Certifi\u00e9 UL\/cUL | LED \u00e0 haute puissance | Sp\u00e9cialiste OEM<\/i><\/p>","protected":false},"excerpt":{"rendered":"<p>4FT Hospital Overbed Light Factory Supplier 1. The Industry Standard  [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":8170,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"footnotes":""},"portfolio_category":[85],"portfolio_skills":[],"portfolio_tags":[],"class_list":["post-8169","avada_portfolio","type-avada_portfolio","status-publish","format-standard","has-post-thumbnail","hentry","portfolio_category-healthcare-lighting"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>4FT Hospital Overbed Light - Prillumen Light Linear Architectural Lighting Manufacturer<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prillumenlight.com\/fr\/product\/4ft-hospital-overbed-light\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4FT Hospital Overbed Light - Prillumen Light Linear Architectural Lighting Manufacturer\" \/>\n<meta property=\"og:description\" content=\"4FT Hospital Overbed Light Factory Supplier 1. The Industry Standard [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prillumenlight.com\/fr\/product\/4ft-hospital-overbed-light\/\" \/>\n<meta property=\"og:site_name\" content=\"Prillumen Light Linear Architectural Lighting Manufacturer\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prillumenlight.com\/wp-content\/uploads\/2026\/04\/4FT-Hospital-Overbed-Light.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prillumenlight.com\\\/product\\\/4ft-hospital-overbed-light\\\/\",\"url\":\"https:\\\/\\\/prillumenlight.com\\\/product\\\/4ft-hospital-overbed-light\\\/\",\"name\":\"4FT Hospital Overbed Light - Prillumen Light Linear Architectural Lighting Manufacturer\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prillumenlight.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prillumenlight.com\\\/product\\\/4ft-hospital-overbed-light\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prillumenlight.com\\\/product\\\/4ft-hospital-overbed-light\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prillumenlight.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/4FT-Hospital-Overbed-Light.webp\",\"datePublished\":\"2026-04-27T03:19:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prillumenlight.com\\\/product\\\/4ft-hospital-overbed-light\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prillumenlight.com\\\/product\\\/4ft-hospital-overbed-light\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/prillumenlight.com\\\/product\\\/4ft-hospital-overbed-light\\\/#primaryimage\",\"url\":\"https:\\\/\\\/prillumenlight.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/4FT-Hospital-Overbed-Light.webp\",\"contentUrl\":\"https:\\\/\\\/prillumenlight.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/4FT-Hospital-Overbed-Light.webp\",\"width\":600,\"height\":600,\"caption\":\"4FT Hospital Overbed Light\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prillumenlight.com\\\/product\\\/4ft-hospital-overbed-light\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prillumenlight.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portfolio\",\"item\":\"https:\\\/\\\/prillumenlight.com\\\/product\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"4FT Hospital Overbed Light\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prillumenlight.com\\\/#website\",\"url\":\"https:\\\/\\\/prillumenlight.com\\\/\",\"name\":\"Prillumen Light Linear Architectural Lighting Manufacturer\",\"description\":\"Precision linear lighting solutions for commercial and retail projects.\",\"alternateName\":\"Prillumen Low MOQ Architectural light factory\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prillumenlight.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lumi\u00e8re de lit d'h\u00f4pital 4FT - Fabricant d\u2019\u00e9clairage architectural lin\u00e9aire Prillumen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prillumenlight.com\/fr\/product\/4ft-hospital-overbed-light\/","og_locale":"fr_CA","og_type":"article","og_title":"4FT Hospital Overbed Light - Prillumen Light Linear Architectural Lighting Manufacturer","og_description":"4FT Hospital Overbed Light Factory Supplier 1. The Industry Standard [...]","og_url":"https:\/\/prillumenlight.com\/fr\/product\/4ft-hospital-overbed-light\/","og_site_name":"Prillumen Light Linear Architectural Lighting Manufacturer","og_image":[{"width":600,"height":600,"url":"https:\/\/prillumenlight.com\/wp-content\/uploads\/2026\/04\/4FT-Hospital-Overbed-Light.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimation du temps de lecture":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/prillumenlight.com\/product\/4ft-hospital-overbed-light\/","url":"https:\/\/prillumenlight.com\/product\/4ft-hospital-overbed-light\/","name":"Lumi\u00e8re de lit d'h\u00f4pital 4FT - Fabricant d\u2019\u00e9clairage architectural lin\u00e9aire Prillumen","isPartOf":{"@id":"https:\/\/prillumenlight.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prillumenlight.com\/product\/4ft-hospital-overbed-light\/#primaryimage"},"image":{"@id":"https:\/\/prillumenlight.com\/product\/4ft-hospital-overbed-light\/#primaryimage"},"thumbnailUrl":"https:\/\/prillumenlight.com\/wp-content\/uploads\/2026\/04\/4FT-Hospital-Overbed-Light.webp","datePublished":"2026-04-27T03:19:25+00:00","breadcrumb":{"@id":"https:\/\/prillumenlight.com\/product\/4ft-hospital-overbed-light\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prillumenlight.com\/product\/4ft-hospital-overbed-light\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/prillumenlight.com\/product\/4ft-hospital-overbed-light\/#primaryimage","url":"https:\/\/prillumenlight.com\/wp-content\/uploads\/2026\/04\/4FT-Hospital-Overbed-Light.webp","contentUrl":"https:\/\/prillumenlight.com\/wp-content\/uploads\/2026\/04\/4FT-Hospital-Overbed-Light.webp","width":600,"height":600,"caption":"4FT Hospital Overbed Light"},{"@type":"BreadcrumbList","@id":"https:\/\/prillumenlight.com\/product\/4ft-hospital-overbed-light\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prillumenlight.com\/"},{"@type":"ListItem","position":2,"name":"Portfolio","item":"https:\/\/prillumenlight.com\/product\/"},{"@type":"ListItem","position":3,"name":"4FT Hospital Overbed Light"}]},{"@type":"WebSite","@id":"https:\/\/prillumenlight.com\/#website","url":"https:\/\/prillumenlight.com\/","name":"Fabricant d'\u00e9clairage architectural lin\u00e9aire Prillumen Light","description":"Solutions d\u2019\u00e9clairage lin\u00e9aire de pr\u00e9cision pour des projets commerciaux et de d\u00e9tail.","alternateName":"Prillumen Low MOQ Architectural light factory","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prillumenlight.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"}]}},"_links":{"self":[{"href":"https:\/\/prillumenlight.com\/fr\/wp-json\/wp\/v2\/avada_portfolio\/8169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prillumenlight.com\/fr\/wp-json\/wp\/v2\/avada_portfolio"}],"about":[{"href":"https:\/\/prillumenlight.com\/fr\/wp-json\/wp\/v2\/types\/avada_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/prillumenlight.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prillumenlight.com\/fr\/wp-json\/wp\/v2\/comments?post=8169"}],"version-history":[{"count":1,"href":"https:\/\/prillumenlight.com\/fr\/wp-json\/wp\/v2\/avada_portfolio\/8169\/revisions"}],"predecessor-version":[{"id":8171,"href":"https:\/\/prillumenlight.com\/fr\/wp-json\/wp\/v2\/avada_portfolio\/8169\/revisions\/8171"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prillumenlight.com\/fr\/wp-json\/wp\/v2\/media\/8170"}],"wp:attachment":[{"href":"https:\/\/prillumenlight.com\/fr\/wp-json\/wp\/v2\/media?parent=8169"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/prillumenlight.com\/fr\/wp-json\/wp\/v2\/portfolio_category?post=8169"},{"taxonomy":"portfolio_skills","embeddable":true,"href":"https:\/\/prillumenlight.com\/fr\/wp-json\/wp\/v2\/portfolio_skills?post=8169"},{"taxonomy":"portfolio_tags","embeddable":true,"href":"https:\/\/prillumenlight.com\/fr\/wp-json\/wp\/v2\/portfolio_tags?post=8169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}