{"id":8169,"date":"2026-04-27T03:19:25","date_gmt":"2026-04-27T03:19:25","guid":{"rendered":"https:\/\/prillumenlight.com\/?post_type=avada_portfolio&#038;p=8169"},"modified":"2026-04-27T03:19:25","modified_gmt":"2026-04-27T03:19:25","slug":"4ft-hospital-overbed-light","status":"publish","type":"avada_portfolio","link":"https:\/\/prillumenlight.com\/de\/product\/4ft-hospital-overbed-light\/","title":{"rendered":"4-Fu\u00df Krankenhaus-Bett\u00fcberlicht"},"content":{"rendered":"<h1 data-path-to-node=\"2\">4FT Krankenhaus-\u00dcberbettlicht Fabriklieferant<code data-path-to-node=\"3\" data-index-in-node=\"5\"><\/code><\/h1>\n<h2 data-path-to-node=\"5\">1. Der Industriestandard f\u00fcr maximale Abdeckung<\/h2>\n<p data-path-to-node=\"6\">Die <b data-path-to-node=\"6\" data-index-in-node=\"4\">4FT <a href=\"https:\/\/prillumenlight.com\/de\/applications\/medical-lighting-suppliers\/\">Hospital Overbed<\/a> Light<\/b> (1200mm) ist die am h\u00e4ufigsten spezifizierte Gr\u00f6\u00dfe f\u00fcr Standardmedizinische Abteilungen und Doppelpatientenzimmer weltweit. Entwickelt, um eine Vollbreitenabdeckung \u00fcber Standardkrankenbetten zu gew\u00e4hrleisten, sorgt dieses 48-Zoll-Leuchtmittel daf\u00fcr, dass es keine \u201cdunklen Zonen\u201d im Patientenbereich gibt.<\/p>\n<p data-path-to-node=\"7\">As a high-capacity <b data-path-to-node=\"7\" data-index-in-node=\"19\">in Deutschland ans\u00e4ssiger Hersteller<\/b>, Prillumen hat die 4FT-Serie so konzipiert, dass sie den strengen, 24\/7-Anforderungen \u00f6ffentlicher Krankenh\u00e4user standh\u00e4lt und gleichzeitig die h\u00f6chste Lichtstromleistung in unserem <b data-path-to-node=\"7\" data-index-in-node=\"194\">Krankenhausbeleuchtung<\/b> Katalog liefert.<\/p>\n<p data-path-to-node=\"7\"><img decoding=\"async\" class=\"lazyload alignnone size-full wp-image-8170\" src=\"https:\/\/prillumenlight.com\/wp-content\/uploads\/2026\/04\/4FT-Hospital-Overbed-Light.webp\" data-orig-src=\"https:\/\/prillumenlight.com\/wp-content\/uploads\/2026\/04\/4FT-Hospital-Overbed-Light.webp\" alt=\"4-Fu\u00df Krankenhaus-Bett\u00fcberlicht\" width=\"600\" height=\"600\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27600%27%20viewBox%3D%270%200%20600%20600%27%3E%3Crect%20width%3D%27600%27%20height%3D%27600%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/prillumenlight.com\/wp-content\/uploads\/2026\/04\/4FT-Hospital-Overbed-Light-12x12.webp 12w, https:\/\/prillumenlight.com\/wp-content\/uploads\/2026\/04\/4FT-Hospital-Overbed-Light-66x66.webp 66w, https:\/\/prillumenlight.com\/wp-content\/uploads\/2026\/04\/4FT-Hospital-Overbed-Light-150x150.webp 150w, https:\/\/prillumenlight.com\/wp-content\/uploads\/2026\/04\/4FT-Hospital-Overbed-Light-200x200.webp 200w, https:\/\/prillumenlight.com\/wp-content\/uploads\/2026\/04\/4FT-Hospital-Overbed-Light-300x300.webp 300w, https:\/\/prillumenlight.com\/wp-content\/uploads\/2026\/04\/4FT-Hospital-Overbed-Light-400x400.webp 400w, https:\/\/prillumenlight.com\/wp-content\/uploads\/2026\/04\/4FT-Hospital-Overbed-Light.webp 600w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p>\n<h2 data-path-to-node=\"9\">2. Flaggschiff-Leistung: 60W Hochleistungs-Spezifikation<\/h2>\n<p data-path-to-node=\"10\">Wenn klinische Pr\u00e4zision unverhandelbar ist, bietet das 4FT-Modell die Leistung und Zuverl\u00e4ssigkeit, die f\u00fcr komplexe <b data-path-to-node=\"10\" data-index-in-node=\"113\">Untersuchungsanforderungen<\/b>.<\/p>\n<table data-path-to-node=\"11\">\n<thead>\n<tr>\n<td><strong>Merkmal<\/strong><\/td>\n<td><strong>Spezifikation<\/strong><\/td>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td><span data-path-to-node=\"11,1,0,0\"><b data-path-to-node=\"11,1,0,0\" data-index-in-node=\"0\">Physikalische L\u00e4nge<\/b><\/span><\/td>\n<td><span data-path-to-node=\"11,1,1,0\">48,58\u2033 (ca. 1230mm)<\/span><\/td>\n<\/tr>\n<tr>\n<td><span data-path-to-node=\"11,2,0,0\"><b data-path-to-node=\"11,2,0,0\" data-index-in-node=\"0\">Systemleistung<\/b><\/span><\/td>\n<td><span data-path-to-node=\"11,2,1,0\">60W (Maximale klinische Intensit\u00e4t)<\/span><\/td>\n<\/tr>\n<tr>\n<td><span data-path-to-node=\"11,3,0,0\"><b data-path-to-node=\"11,3,0,0\" data-index-in-node=\"0\">Lumen Efficacy<\/b><\/span><\/td>\n<td><span data-path-to-node=\"11,3,1,0\">115 lm\/W<\/span><\/td>\n<\/tr>\n<tr>\n<td><span data-path-to-node=\"11,4,0,0\"><b data-path-to-node=\"11,4,0,0\" data-index-in-node=\"0\">Gesamtlichtstrom<\/b><\/span><\/td>\n<td><span data-path-to-node=\"11,4,1,0\">6.900 Lumen<\/span><\/td>\n<\/tr>\n<tr>\n<td><span data-path-to-node=\"11,5,0,0\"><b data-path-to-node=\"11,5,0,0\" data-index-in-node=\"0\">Lichtverteilung<\/b><\/span><\/td>\n<td><span data-path-to-node=\"11,5,1,0\">60% Downlight \/ 40% Up-Light (Standard)<\/span><\/td>\n<\/tr>\n<tr>\n<td><span data-path-to-node=\"11,6,0,0\"><b data-path-to-node=\"11,6,0,0\" data-index-in-node=\"0\">Konstruktion<\/b><\/span><\/td>\n<td><span data-path-to-node=\"11,6,1,0\">Industrielle Extrusionsaluminiumqualit\u00e4t<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2 data-path-to-node=\"13\">3. Wichtige Vorteile f\u00fcr gro\u00df angelegte Gesundheitseinrichtungen<\/h2>\n<h3 data-path-to-node=\"14\">A. Maximale Untersuchungsfeldabdeckung<\/h3>\n<p data-path-to-node=\"15\">Mit 6.900 Lumen bei Spitzenleistung bietet das 4FT-Leuchtmittel eine gro\u00dfz\u00fcgige <b data-path-to-node=\"15\" data-index-in-node=\"72\">Pr\u00fcfmodus<\/b> Lichtfeld. Dies erm\u00f6glicht \u00c4rzten und Pflegekr\u00e4ften, Eingriffe mit absoluter Klarheit durchzuf\u00fchren und sicherzustellen, dass Schatten im gesamten 4-Fu\u00df-Klinikarbeitsbereich minimiert werden.<\/p>\n<h3 data-path-to-node=\"16\">B. \u00dcberragende Blendungsbegrenzung f\u00fcr Mehrbettzimmer<\/h3>\n<p data-path-to-node=\"17\">In Zweibettzimmern kann Lichtaustritt ein gro\u00dfes Problem darstellen. Unsere 4FT <b data-path-to-node=\"17\" data-index-in-node=\"65\">Beleuchtungsk\u00f6rpern<\/b> nutzen fortschrittliche <b data-path-to-node=\"17\" data-index-in-node=\"100\">Lichtdiffusoren<\/b> und mikroprismatische Linsen, um sicherzustellen, dass das vorgesehene Bett brillant beleuchtet wird, w\u00e4hrend die Blendung kontrolliert bleibt, um den Komfort des Patienten im angrenzenden Bett zu sch\u00fctzen.<\/p>\n<h3 data-path-to-node=\"18\">C. Industrielle Haltbarkeit<\/h3>\n<p data-path-to-node=\"19\">\u00d6ffentliche Krankenh\u00e4user ben\u00f6tigen <b data-path-to-node=\"19\" data-index-in-node=\"25\">Leuchten<\/b> die auf Langlebigkeit ausgelegt sind. Unsere 4FT-Serie verf\u00fcgt \u00fcber ein schlagfestes Geh\u00e4use und eine hochbelastbare <b data-path-to-node=\"19\" data-index-in-node=\"129\">antimikrobielle Beschichtung<\/b> die den aggressivsten chemischen Desinfektionsprotokollen standh\u00e4lt, die in stark frequentierten Bereichen verwendet werden <b data-path-to-node=\"19\" data-index-in-node=\"234\">Gesundheitseinrichtungen<\/b>.<\/p>\n<hr data-path-to-node=\"20\" \/>\n<h2 data-path-to-node=\"21\">4. Prim\u00e4re Anwendungsszenarien<\/h2>\n<h3 data-path-to-node=\"22\">\ud83c\udfe5 Allgemeine Stationen \u00f6ffentlicher Krankenh\u00e4user<\/h3>\n<p data-path-to-node=\"23\">Das 48-Zoll-Modell ist der bevorzugte Standard f\u00fcr Projekte in staatlichen und \u00f6ffentlichen Krankenh\u00e4usern, da es die M\u00f6glichkeit bietet, <b data-path-to-node=\"23\" data-index-in-node=\"118\">angemessene Beleuchtung<\/b> sowohl f\u00fcr die allgemeine Patientenversorgung als auch f\u00fcr Notfalleingriffe am Bett.<\/p>\n<h3 data-path-to-node=\"24\">\ud83d\udecc Doppel-\/Mehrbettzimmer<\/h3>\n<p data-path-to-node=\"25\">Die L\u00e4nge der 4FT-Leuchte macht sie ideal f\u00fcr R\u00e4ume, in denen Betten eng beieinander stehen, da eine Leuchte oft als prim\u00e4re Lichtquelle f\u00fcr den unmittelbaren Bettbereich dienen kann.<\/p>\n<h3 data-path-to-node=\"26\">\ud83e\uddea Spezialisierte Klinische Einheiten<\/h3>\n<p data-path-to-node=\"27\">Perfekt f\u00fcr Traumazentren, chirurgische Aufwachstationen und Intensivpflegebereiche, wo die <b data-path-to-node=\"27\" data-index-in-node=\"88\">Untersuchungsanforderungen<\/b> am h\u00f6chsten sind.<\/p>\n<h2 data-path-to-node=\"29\">5. Gro\u00dfhandel &amp; Projektunterst\u00fctzung von unserer Fabrik<\/h2>\n<p data-path-to-node=\"30\">Prillumen spezialisiert sich auf die Unterst\u00fctzung bei gro\u00df angelegten Ausschreibungen und Sammelbeschaffungen f\u00fcr internationale Krankenhausgruppen.<\/p>\n<ul data-path-to-node=\"31\">\n<li>\n<p data-path-to-node=\"31,0,0\"><b data-path-to-node=\"31,0,0\" data-index-in-node=\"0\">Projektbereite Logistik:<\/b> Wir bieten optimierte Verpackungen f\u00fcr die 1200mm Einheiten an, um einen sicheren, kosteng\u00fcnstigen internationalen Versand f\u00fcr Bestellungen \u00fcber 500 Einheiten zu gew\u00e4hrleisten.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"31,1,0\"><b data-path-to-node=\"31,1,0\" data-index-in-node=\"0\">Vollst\u00e4ndige Konformit\u00e4t:<\/b> Unsere 4FT-Leuchten sind <b data-path-to-node=\"31,1,0\" data-index-in-node=\"38\">UL\/cUL gelistet<\/b> und erf\u00fcllen <b data-path-to-node=\"31,1,0\" data-index-in-node=\"61\">DLC Premium<\/b> Standards, um Energierabatte f\u00fcr gro\u00dfe Anlagenmodernisierungen zu maximieren.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"31,2,0\"><b data-path-to-node=\"31,2,0\" data-index-in-node=\"0\">Experten-Submittals:<\/b> Wir stellen alle notwendigen Dokumentationen bereit, einschlie\u00dflich IES-Dateien, W\u00e4rmeleitungstests und <b data-path-to-node=\"31,2,0\" data-index-in-node=\"106\">antimikrobielle Beschichtung<\/b> Zertifizierungen, um Ihnen bei der Gewinnung Ihres n\u00e4chsten Angebots zu helfen.<\/p>\n<\/li>\n<\/ul>\n<h2 data-path-to-node=\"33\">6. 4FT-Serie Professionelle FAQ<\/h2>\n<p data-path-to-node=\"34\"><b data-path-to-node=\"34\" data-index-in-node=\"0\">F: Ist eine 4FT-Leuchte zu hell f\u00fcr einen einzelnen Patienten?<\/b><\/p>\n<p data-path-to-node=\"34\">A: \u00dcberhaupt nicht. Dank der <b data-path-to-node=\"34\" data-index-in-node=\"82\">unabh\u00e4ngige Hoch- und Runtersteuerung<\/b>, kann der Patient das weiche <b data-path-to-node=\"34\" data-index-in-node=\"140\">Ambientmodus<\/b> (Auflicht) f\u00fcr eine entspannende Umgebung nutzen. Die volle Leistung von 60W wird nur w\u00e4hrend <b data-path-to-node=\"34\" data-index-in-node=\"233\">Pr\u00fcfmodus<\/b> oder wenn klinisch hochintensives Licht notwendig ist, aktiviert.<\/p>\n<p data-path-to-node=\"35\"><b data-path-to-node=\"35\" data-index-in-node=\"0\">F: Wie beeinflusst das Gewicht des 4FT-Modells die Installation?<\/b><\/p>\n<p data-path-to-node=\"35\">A: Trotz ihrer robusten Aluminiumkonstruktion bleibt die Leuchte leicht genug f\u00fcr eine Einzelperson bei der Installation. Die <b data-path-to-node=\"35\" data-index-in-node=\"187\">Wandmontage<\/b> Halterungssystem ist f\u00fcr eine schnelle Ausrichtung \u00fcber Standard-Elektroboxen ausgelegt.<\/p>\n<p data-path-to-node=\"36\"><b data-path-to-node=\"36\" data-index-in-node=\"0\">F: K\u00f6nnen wir diese mit einer integrierten Notstrombatterie (EM) bestellen?<\/b><\/p>\n<p data-path-to-node=\"36\">A: Ja. F\u00fcr gro\u00dfe Krankenhausprojekte k\u00f6nnen wir die 4FT-Serie mit einem internen EM-Treiber ausstatten, der 90 Minuten lang Energie liefert <b data-path-to-node=\"36\" data-index-in-node=\"185\">angemessene Beleuchtung<\/b> w\u00e4hrend Stromausf\u00e4llen und alle lebensrettenden Vorschriften erf\u00fcllt.<\/p>\n<p data-path-to-node=\"37\"><b data-path-to-node=\"37\" data-index-in-node=\"0\">F: Ist das 4FT-Modell CCT ausw\u00e4hlbar?<\/b><\/p>\n<p data-path-to-node=\"37\">A: Ja. Wie unsere anderen Modelle verf\u00fcgt die 4FT-Version \u00fcber <b data-path-to-node=\"37\" data-index-in-node=\"92\">CCT w\u00e4hlbar<\/b> Schalter, mit denen Sie zwischen 3000K, 4000K oder 5000K w\u00e4hlen k\u00f6nnen, um die bestehende Beleuchtung in Ihrer Einrichtung anzupassen.<\/p>\n<h2 data-path-to-node=\"39\">7. Skalieren Sie Ihre Einrichtung mit Prillumen<\/h2>\n<p data-path-to-node=\"40\">F\u00fcr Hochleistungs-, langlebige und hochwertige <b data-path-to-node=\"40\" data-index-in-node=\"54\">Krankenhaus\u00fcberbettlichter<\/b>, ist die Prillumen 4FT-Serie die erste Wahl f\u00fcr professionelle Planer.<\/p>\n<p data-path-to-node=\"43\"><b data-path-to-node=\"43\" data-index-in-node=\"0\">Prillumen: Die Zukunft der \u00f6ffentlichen Gesundheitsversorgung gestalten.<\/b><\/p>\n<p data-path-to-node=\"43\"><i data-path-to-node=\"43\" data-index-in-node=\"53\">UL\/cUL-zertifiziert | Hochleistungs-LED | OEM-Spezialist<\/i><\/p>","protected":false},"excerpt":{"rendered":"<p>4FT Hospital Overbed Light Factory Supplier 1. The Industry Standard  [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":8170,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"footnotes":""},"portfolio_category":[85],"portfolio_skills":[],"portfolio_tags":[],"class_list":["post-8169","avada_portfolio","type-avada_portfolio","status-publish","format-standard","has-post-thumbnail","hentry","portfolio_category-healthcare-lighting"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>4FT Hospital Overbed Light - Prillumen Light Linear Architectural Lighting Manufacturer<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prillumenlight.com\/de\/product\/4ft-hospital-overbed-light\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4FT Hospital Overbed Light - Prillumen Light Linear Architectural Lighting Manufacturer\" \/>\n<meta property=\"og:description\" content=\"4FT Hospital Overbed Light Factory Supplier 1. The Industry Standard [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prillumenlight.com\/de\/product\/4ft-hospital-overbed-light\/\" \/>\n<meta property=\"og:site_name\" content=\"Prillumen Light Linear Architectural Lighting Manufacturer\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prillumenlight.com\/wp-content\/uploads\/2026\/04\/4FT-Hospital-Overbed-Light.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prillumenlight.com\\\/product\\\/4ft-hospital-overbed-light\\\/\",\"url\":\"https:\\\/\\\/prillumenlight.com\\\/product\\\/4ft-hospital-overbed-light\\\/\",\"name\":\"4FT Hospital Overbed Light - Prillumen Light Linear Architectural Lighting Manufacturer\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prillumenlight.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prillumenlight.com\\\/product\\\/4ft-hospital-overbed-light\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prillumenlight.com\\\/product\\\/4ft-hospital-overbed-light\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prillumenlight.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/4FT-Hospital-Overbed-Light.webp\",\"datePublished\":\"2026-04-27T03:19:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prillumenlight.com\\\/product\\\/4ft-hospital-overbed-light\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prillumenlight.com\\\/product\\\/4ft-hospital-overbed-light\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/prillumenlight.com\\\/product\\\/4ft-hospital-overbed-light\\\/#primaryimage\",\"url\":\"https:\\\/\\\/prillumenlight.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/4FT-Hospital-Overbed-Light.webp\",\"contentUrl\":\"https:\\\/\\\/prillumenlight.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/4FT-Hospital-Overbed-Light.webp\",\"width\":600,\"height\":600,\"caption\":\"4FT Hospital Overbed Light\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prillumenlight.com\\\/product\\\/4ft-hospital-overbed-light\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prillumenlight.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portfolio\",\"item\":\"https:\\\/\\\/prillumenlight.com\\\/product\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"4FT Hospital Overbed Light\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prillumenlight.com\\\/#website\",\"url\":\"https:\\\/\\\/prillumenlight.com\\\/\",\"name\":\"Prillumen Light Linear Architectural Lighting Manufacturer\",\"description\":\"Precision linear lighting solutions for commercial and retail projects.\",\"alternateName\":\"Prillumen Low MOQ Architectural light factory\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prillumenlight.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"4FT Krankenhausbett\u00fcberlicht - Prillumen Licht Linear Architektonische Beleuchtungshersteller","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prillumenlight.com\/de\/product\/4ft-hospital-overbed-light\/","og_locale":"de_DE","og_type":"article","og_title":"4FT Hospital Overbed Light - Prillumen Light Linear Architectural Lighting Manufacturer","og_description":"4FT Hospital Overbed Light Factory Supplier 1. The Industry Standard [...]","og_url":"https:\/\/prillumenlight.com\/de\/product\/4ft-hospital-overbed-light\/","og_site_name":"Prillumen Light Linear Architectural Lighting Manufacturer","og_image":[{"width":600,"height":600,"url":"https:\/\/prillumenlight.com\/wp-content\/uploads\/2026\/04\/4FT-Hospital-Overbed-Light.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/prillumenlight.com\/product\/4ft-hospital-overbed-light\/","url":"https:\/\/prillumenlight.com\/product\/4ft-hospital-overbed-light\/","name":"4FT Krankenhausbett\u00fcberlicht - Prillumen Licht Linear Architektonische Beleuchtungshersteller","isPartOf":{"@id":"https:\/\/prillumenlight.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prillumenlight.com\/product\/4ft-hospital-overbed-light\/#primaryimage"},"image":{"@id":"https:\/\/prillumenlight.com\/product\/4ft-hospital-overbed-light\/#primaryimage"},"thumbnailUrl":"https:\/\/prillumenlight.com\/wp-content\/uploads\/2026\/04\/4FT-Hospital-Overbed-Light.webp","datePublished":"2026-04-27T03:19:25+00:00","breadcrumb":{"@id":"https:\/\/prillumenlight.com\/product\/4ft-hospital-overbed-light\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prillumenlight.com\/product\/4ft-hospital-overbed-light\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/prillumenlight.com\/product\/4ft-hospital-overbed-light\/#primaryimage","url":"https:\/\/prillumenlight.com\/wp-content\/uploads\/2026\/04\/4FT-Hospital-Overbed-Light.webp","contentUrl":"https:\/\/prillumenlight.com\/wp-content\/uploads\/2026\/04\/4FT-Hospital-Overbed-Light.webp","width":600,"height":600,"caption":"4FT Hospital Overbed Light"},{"@type":"BreadcrumbList","@id":"https:\/\/prillumenlight.com\/product\/4ft-hospital-overbed-light\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prillumenlight.com\/"},{"@type":"ListItem","position":2,"name":"Portfolio","item":"https:\/\/prillumenlight.com\/product\/"},{"@type":"ListItem","position":3,"name":"4FT Hospital Overbed Light"}]},{"@type":"WebSite","@id":"https:\/\/prillumenlight.com\/#website","url":"https:\/\/prillumenlight.com\/","name":"Prillumen Light Linear Architektonische Beleuchtungshersteller","description":"Pr\u00e4zise lineare Beleuchtungsl\u00f6sungen f\u00fcr gewerbliche und Einzelhandelsprojekte.","alternateName":"Prillumen Low MOQ Architectural light factory","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prillumenlight.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/prillumenlight.com\/de\/wp-json\/wp\/v2\/avada_portfolio\/8169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prillumenlight.com\/de\/wp-json\/wp\/v2\/avada_portfolio"}],"about":[{"href":"https:\/\/prillumenlight.com\/de\/wp-json\/wp\/v2\/types\/avada_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/prillumenlight.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prillumenlight.com\/de\/wp-json\/wp\/v2\/comments?post=8169"}],"version-history":[{"count":1,"href":"https:\/\/prillumenlight.com\/de\/wp-json\/wp\/v2\/avada_portfolio\/8169\/revisions"}],"predecessor-version":[{"id":8171,"href":"https:\/\/prillumenlight.com\/de\/wp-json\/wp\/v2\/avada_portfolio\/8169\/revisions\/8171"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prillumenlight.com\/de\/wp-json\/wp\/v2\/media\/8170"}],"wp:attachment":[{"href":"https:\/\/prillumenlight.com\/de\/wp-json\/wp\/v2\/media?parent=8169"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/prillumenlight.com\/de\/wp-json\/wp\/v2\/portfolio_category?post=8169"},{"taxonomy":"portfolio_skills","embeddable":true,"href":"https:\/\/prillumenlight.com\/de\/wp-json\/wp\/v2\/portfolio_skills?post=8169"},{"taxonomy":"portfolio_tags","embeddable":true,"href":"https:\/\/prillumenlight.com\/de\/wp-json\/wp\/v2\/portfolio_tags?post=8169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}